{"id":25480,"date":"2021-09-01T13:35:00","date_gmt":"2021-09-01T11:35:00","guid":{"rendered":"https:\/\/www.bellitalie.org\/destination\/piemonte\/torino\/chateau-royal-de-moncalieri\/"},"modified":"2023-10-11T10:50:21","modified_gmt":"2023-10-11T08:50:21","slug":"castello-reale-di-moncalieri","status":"publish","type":"destination","link":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/","title":{"rendered":"Castello Reale di Moncalieri"},"content":{"rendered":"\n<p>Il <strong>Castello di Moncalieri<\/strong> \u00e8 un&#8217;altra delle residenze sabaude, che si trova nei dintorni di Torino. In cima al paese di <strong>Moncalieri<\/strong> fu costruito nel XVII secolo ampliando una fortezza medievale.<br \/>Il palazzo fu pi\u00f9 volte dimora dei sovrani e dei nobili, tra cui Emanuele Filiberto o Carlo Emanuele I che decise di ingrandirlo, facendo intervenire per decenni grandi architetti come Amedeo di Castellamonte, Andrea Costaguta e Carlo Morello.<br \/>Con i restauri degli inizi del XIX secolo fu costruita la scala a tre rampe in marmo di Carrara. Nel 1831 Carlo Alberto di Savoia vi stabil\u00ec la sua residenza. Dopo la seconda guerra mondiale divenne sede del primo battaglione carabinieri piemontese.<br \/>Un grande incendio distrusse nel 2008 un dungeon e gli appartamenti reali, e il castello fu chiuso al pubblico fino al 2017.<\/p>\n\n\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" data-id=\"16351\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716-1024x683.jpg\" alt=\"foto del castello di moncalieri_5716\" class=\"wp-image-16351\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Castello di Moncalieri<\/figcaption><\/figure>\n<\/figure>\n\n\n<p>Oggi \u00e8 possibile visitare al piano terra gli appartamenti di Maria Letizia con i suoi soffitti settecenteschi, la bella sala ricevimenti, la camera della principessa con un grande servizio in stile neo-luigi XVI e il Gabinetto Cinese.<br \/>La scala d&#8217;onore conduce al piano nobile con l&#8217;appartamento di Vittorio Emanuele II e di sua moglie Maria Adelaide d&#8217;Asburgo-Lorena, tra cui il Salone della Regina con le sue decorazioni in legno di rosa, la camera della regina, il bagno privato del re, o l&#8217;elegante cappella reale del XVIII secolo.<\/p>\n<h2>Cartina ed indirizzo<\/h2>\n<p>Piazza Baden Baden, 4, 10024 Moncalieri TO<br \/><div id=\"travelersmap-container-6a573a22c3646\" class=\"travelersmap-container\" style=\"z-index: 1; min-height: 10px; min-width:10px; height:450px;width:100%; max-width:; max-height:; position:relative;\"><div style=\"position:absolute; z-index:-1;top: 50%;text-align: center;display: block;left: 50%;transform: translate(-50%,-50%);\">Travelers' Map is loading... <br> If you see this after your page is loaded completely, leafletJS files are missing.<\/div><\/div>\n<h2>Informazioni<\/h2>\n<ul>\n<li>Sito ufficiale : <a href=\"https:\/\/www.castellodimoncalieri.it\/\" target=\"_blank\" rel=\"noopener\">www.castellodimoncalieri.it<\/a><\/li>\n<li>Articolo Wikipedia : <a href=\"https:\/\/it.wikipedia.org\/wiki\/Castello_di_Moncalieri\" target=\"_blank\" rel=\"noopener\">Castello di Moncalieri<\/a><\/li>\n<\/ul>\n\n\n<div class=\"wp-container-5 wp-block-columns has-background\" style=\"background-color:#dfece5\">\n<div class=\"wp-container-3 wp-block-column\">\n<p><a href=\"https:\/\/www.bellitalie.org\/it\/regione_italia\/piemonte\/\" target=\"_blank\" rel=\"noopener\"><strong>Piemonte<\/strong><\/a><\/p>\n<ul class=\"lcp_catlist2\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/cose-da-vedere-in-piemonte\/\">Cose da vedere in Piemonte<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/cose-da-vedere-in-piemonte\/\" title=\"Cose da vedere in Piemonte\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5085-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Cose da vedere in Piemonte\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5085-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5085-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5085-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5085-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">Le citt\u00e0, luoghi e siti da vedere nella regione Piemonte, da Torino la capitale con ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/\">Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/\" title=\"Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nPur essendo nota soprattutto per essere un importante centro industriale, con le sue immense fabbriche ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/sacra-di-san-michele\/\">Sacra di San Michele<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/sacra-di-san-michele\/\" title=\"Sacra di San Michele\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5078-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Sacra di San Michele\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5078-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5078-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5078-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/abbaye-saint-michel-de-la-cluse_5078-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">La Sacra di San Michele della Chiusa, all&#8217;entrata della Val di Susa, \u00e8 arroccata sul ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-maggiore\/\">Lago Maggiore<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-maggiore\/\" title=\"Lago Maggiore\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago Maggiore\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Lago Maggiore \u00e8 una delle pi\u00f9 belle destinazioni del nord Italia, la cui sponda ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/\">Val di Susa<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/\" title=\"Val di Susa\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/panorama-vallee-de-suse-abbaye-saint-michel-de-la-cluse_5113-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Val di Susa\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/panorama-vallee-de-suse-abbaye-saint-michel-de-la-cluse_5113-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/panorama-vallee-de-suse-abbaye-saint-michel-de-la-cluse_5113-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/panorama-vallee-de-suse-abbaye-saint-michel-de-la-cluse_5113-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/panorama-vallee-de-suse-abbaye-saint-michel-de-la-cluse_5113-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">La Val di Susa \u00e8 una bella valle alpina che conduce da Torino verso le ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/lago-d-orta\/\">Lago d&#8217;Orta<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/lago-d-orta\/\" title=\"Lago d&#039;Orta\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/panorama-lac-d-orta-mont-sacre-orta_6800-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago d&#039;Orta\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/panorama-lac-d-orta-mont-sacre-orta_6800-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/panorama-lac-d-orta-mont-sacre-orta_6800-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/panorama-lac-d-orta-mont-sacre-orta_6800-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/panorama-lac-d-orta-mont-sacre-orta_6800-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nA pochi chilometri ad ovest del Lago Maggiore, il Lago d&#8217;Orta \u00e8 una destinazione affascinante ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/langhe\/alba\/\">Alba<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/langhe\/alba\/\" title=\"Alba\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-duomo-alba-langhe_4711-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Alba\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-duomo-alba-langhe_4711-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-duomo-alba-langhe_4711-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-duomo-alba-langhe_4711-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-duomo-alba-langhe_4711-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nCapitale delle Langhe, Alba fu un potente insediamento romano, oggi una piccola citt\u00e0 che \u00e8 ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/asti\/\">Asti<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/asti\/\" title=\"Asti\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/asti_7883-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Asti\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/asti_7883-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/asti_7883-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/asti_7883-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/asti_7883-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nAsti \u00e8 capoluogo dell&#8217;omonima provincia, in Piemonte, abitata nel 2021 da quasi 14.000 abitanti. Si ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/cuneo-e-dintorni-2\/\">Cuneo e dintorni<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/cuneo-e-dintorni-2\/\" title=\"Cuneo e dintorni\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/07\/santuario-di-san-magno_0506-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Cuneo e dintorni\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/07\/santuario-di-san-magno_0506-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/07\/santuario-di-san-magno_0506-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/07\/santuario-di-san-magno_0506-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/07\/santuario-di-san-magno_0506-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">Graziosa e accogliente citt\u00e0, Cuneo si trova ai piedi delle Alpi alla confluenza di due ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/langhe\/\">Langhe<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/langhe\/\" title=\"Langhe\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/vista-barolo-monteforte-d-alba_6285-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Langhe\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/vista-barolo-monteforte-d-alba_6285-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/vista-barolo-monteforte-d-alba_6285-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/vista-barolo-monteforte-d-alba_6285-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/vista-barolo-monteforte-d-alba_6285-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">Il territorio delle Langhe \u00e8 una terra di vini elaborati, con le sue colline coperte ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/monferrato-astigiano-e-basso\/\">Monferrata Astigiano e Basso Monferrato<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/monferrato-astigiano-e-basso\/\" title=\"Monferrata Astigiano e Basso Monferrato\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/10\/montiglio-monferrato_6351-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Monferrata Astigiano e Basso Monferrato\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/10\/montiglio-monferrato_6351-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/10\/montiglio-monferrato_6351-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/10\/montiglio-monferrato_6351-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/10\/montiglio-monferrato_6351-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">Il Monferrato Astigiano e il Basso Monferrato a nord e ad ovest della provincia di ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/roero-e-dintorni\">Roero e dintorni<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/roero-e-dintorni\" title=\"Roero e dintorni\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/03\/parco-giardini-della-rocca-bra_6201-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Roero e dintorni\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/03\/parco-giardini-della-rocca-bra_6201-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/03\/parco-giardini-della-rocca-bra_6201-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/03\/parco-giardini-della-rocca-bra_6201-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/03\/parco-giardini-della-rocca-bra_6201-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Roero \u00e8 con le Langhe e il Monferrato l&#8217;altra regione vinicola storica del Piemonte, ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/domodossola-e-valli-ossolane\/\">Domodossola e Valli Ossolane<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/domodossola-e-valli-ossolane\/\" title=\"Domodossola e Valli Ossolane\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/domodossola_1461-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Domodossola e Valli Ossolane\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/domodossola_1461-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/domodossola_1461-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/domodossola_1461-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/domodossola_1461-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nValli Ossolane\nA nord-ovest del Lago Maggiore, le Valli Ossolane sono una bellissima piccola regione con ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/la-valsesia\/\">La Valsesia<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/la-valsesia\/\" title=\"La Valsesia\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/08\/mont-sacre-de-varallo_6659-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"La Valsesia\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/08\/mont-sacre-de-varallo_6659-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/08\/mont-sacre-de-varallo_6659-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/08\/mont-sacre-de-varallo_6659-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/08\/mont-sacre-de-varallo_6659-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nMeno frequentata delle vicine valli alpine, la Valsesia ha tuttavia interessanti ricchezze naturali e culturali. ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/saluzzo-e-dintorni\/\">Saluzzo e dintorni<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/saluzzo-e-dintorni\/\" title=\"Saluzzo e dintorni\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/torre-civico-saluzzo_6222-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Saluzzo e dintorni\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/torre-civico-saluzzo_6222-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/torre-civico-saluzzo_6222-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/torre-civico-saluzzo_6222-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/torre-civico-saluzzo_6222-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nAi piedi dei contrafforti alpini del Monviso, Saluzzo \u00e8 una picola citt\u00e0 di circa 17.000 ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/susa\/\">Susa<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/susa\/\" title=\"Susa\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/suse-italie_7843-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Susa\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/suse-italie_7843-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/suse-italie_7843-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/suse-italie_7843-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/suse-italie_7843-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nSusa \u00e8 una piccola citt\u00e0 della Val di Susa, che conserva dalla sua lunga storia ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/il-canavese-e-il-biellese-a-nord-di-torino\/#Sacro_Monte_di_Oropa\">Sacro Monte di Oropa<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/il-canavese-e-il-biellese-a-nord-di-torino\/#Sacro_Monte_di_Oropa\" title=\"Sacro Monte di Oropa\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/monte-sacro-di-oropa_5680-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Sacro Monte di Oropa\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/monte-sacro-di-oropa_5680-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/monte-sacro-di-oropa_5680-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/monte-sacro-di-oropa_5680-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/monte-sacro-di-oropa_5680-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">Il pi\u00f9 famoso e grandioso dei Sacri Monti si trova sul Monte di Oropa, al ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/usseaux-e-forte-di-fenestrelle\/\">Usseaux e Forte di Fenestrelle<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/val-di-susa\/usseaux-e-forte-di-fenestrelle\/\" title=\"Usseaux e Forte di Fenestrelle\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2024\/04\/forteresse-de-fenestrelle-piemont_4684-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Usseaux e Forte di Fenestrelle\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2024\/04\/forteresse-de-fenestrelle-piemont_4684-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2024\/04\/forteresse-de-fenestrelle-piemont_4684-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2024\/04\/forteresse-de-fenestrelle-piemont_4684-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2024\/04\/forteresse-de-fenestrelle-piemont_4684-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Val Chisone \u00e8 a sud del Val di Susa, a est della stazione sciistica ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/casale-monferrato\/\">Casale Monferrato<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/casale-monferrato\/\" title=\"Casale Monferrato\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/casale-monferrato_6570-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Casale Monferrato\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/casale-monferrato_6570-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/casale-monferrato_6570-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/casale-monferrato_6570-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/casale-monferrato_6570-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nRisalente all&#8217;antichit\u00e0 romana, Casale Monferrato \u00e8 una graziosa e tranquilla cittadina con belle chiese, portici, ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/vercelli\/\">Vercelli<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/vercelli\/\" title=\"Vercelli\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-cavour-vercelli_6436-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Vercelli\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-cavour-vercelli_6436-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-cavour-vercelli_6436-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-cavour-vercelli_6436-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-cavour-vercelli_6436-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nVercelli non \u00e8 la citt\u00e0 pi\u00f9 conosciuta della regione, di cui gli italiani stessi non ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/il-canavese-e-il-biellese-a-nord-di-torino\/\">Ivrea, il Canavese ed il Biellese<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/il-canavese-e-il-biellese-a-nord-di-torino\/\" title=\"Ivrea, il Canavese ed il Biellese\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/castello-ducale-di-aglie_5367-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Ivrea, il Canavese ed il Biellese\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/castello-ducale-di-aglie_5367-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/castello-ducale-di-aglie_5367-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/castello-ducale-di-aglie_5367-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/11\/castello-ducale-di-aglie_5367-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">Il Canavese ha come capitale Ivrea, nelle colline prealpine a nord di Torino, e il ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/novara\/\">Novara<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/novara\/\" title=\"Novara\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/cupola-di-san-gaudenzio-novara_6622-1-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Novara\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/cupola-di-san-gaudenzio-novara_6622-1-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/cupola-di-san-gaudenzio-novara_6622-1-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/cupola-di-san-gaudenzio-novara_6622-1-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/cupola-di-san-gaudenzio-novara_6622-1-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nA est del Piemonte e a sud del Lago Maggiore, Novara \u00e8 la seconda citt\u00e0 ...<\/div><\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-container-4 wp-block-column\">\n<p><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/cose-da-vedere-in-piemonte\/\" target=\"_blank\" rel=\"noopener\"><strong>Torino<\/strong><\/a><\/p>\n<ul class=\"lcp_catlist2\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/cosa-vedere-a-torino\/\">Cosa vedere a Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/cosa-vedere-a-torino\/\" title=\"Cosa vedere a Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/turin_palais_royal_7954-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Cosa vedere a Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/turin_palais_royal_7954-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/turin_palais_royal_7954-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/turin_palais_royal_7954-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/turin_palais_royal_7954-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nVedi anche sotto la mappa interattiva di Torino con le principali attrazioni della citt\u00e0.\n1. Piazza ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/piazza-castello-di-torino\/\">Piazza Castello di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/piazza-castello-di-torino\/\" title=\"Piazza Castello di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/piazza-castello-torino_5751-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Piazza Castello di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/piazza-castello-torino_5751-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/piazza-castello-torino_5751-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/piazza-castello-torino_5751-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/piazza-castello-torino_5751-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nPiazza Castello \u00e8 una piazza pedonale da secoli nel cuore di Torino, centro storico del ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/palazzo-e-musei-reali-di-torino\/\">Palazzo e Musei Reali di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/palazzo-e-musei-reali-di-torino\/\" title=\"Palazzo e Musei Reali di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Palazzo e Musei Reali di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-reale-torino_7953-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl sontuoso Palazzo Reale di Torino, residenza sabauda, \u00e8 oggi integrato nei Musei Reali. Questi ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/museo-egizio-di-torino\/\">Museo Egizio di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/museo-egizio-di-torino\/\" title=\"Museo Egizio di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/sarcofago-museo-egizio-torino_6026-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Museo Egizio di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/sarcofago-museo-egizio-torino_6026-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/sarcofago-museo-egizio-torino_6026-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/sarcofago-museo-egizio-torino_6026-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/05\/sarcofago-museo-egizio-torino_6026-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Museo delle Antichit\u00e0 Egizie di Torino \u00e8 il secondo museo al mondo dedicato al ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/mole-antonelliana-torino\/\">Mole Antonelliana<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/mole-antonelliana-torino\/\" title=\"Mole Antonelliana\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/mole-antonelliana-torino_8003-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Mole Antonelliana\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/mole-antonelliana-torino_8003-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/mole-antonelliana-torino_8003-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/mole-antonelliana-torino_8003-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/mole-antonelliana-torino_8003-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nLa Mole Antonelliana \u00e8 associata all&#8217;immagine di Torino di cui \u00e8 diventata il simbolo. Questo ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/cattedrale-di-san-giovanni-battista-torino\/\">Cattedrale di San Giovanni Battista di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/cattedrale-di-san-giovanni-battista-torino\/\" title=\"Cattedrale di San Giovanni Battista di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-san-giovanni_battista-torino_6124-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Cattedrale di San Giovanni Battista di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-san-giovanni_battista-torino_6124-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-san-giovanni_battista-torino_6124-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-san-giovanni_battista-torino_6124-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-san-giovanni_battista-torino_6124-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nLa Cattedrale di San Giovanni Battista \u00e8 una delle poche chiese rinascimentali della zona di ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/piazza-san-carlo-di-torino\/\">Piazza San Carlo di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/piazza-san-carlo-di-torino\/\" title=\"Piazza San Carlo di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-san-carlo-torino_6099-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Piazza San Carlo di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-san-carlo-torino_6099-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-san-carlo-torino_6099-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-san-carlo-torino_6099-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/piazza-san-carlo-torino_6099-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nGrande piazza pedonale di Torino, Piazza San Carlo \u00e8 probabilmente la pi\u00f9 bella della citt\u00e0 ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/palazzo-madama\/\">Palazzo Madama<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/palazzo-madama\/\" title=\"Palazzo Madama\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-madame-turin_5894-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Palazzo Madama\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-madame-turin_5894-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-madame-turin_5894-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-madame-turin_5894-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-madame-turin_5894-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nSituato in Piazza Castello, il Palazzo Madama \u00e8 uno degli edifici pi\u00f9 importanti della regione, ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/porta-palatina-di-torino\/\">Porta Palatina di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/porta-palatina-di-torino\/\" title=\"Porta Palatina di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/porta-palatina-torino_7968-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Porta Palatina di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/porta-palatina-torino_7968-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/porta-palatina-torino_7968-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/porta-palatina-torino_7968-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/porta-palatina-torino_7968-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nAll&#8217;interno di una piccola area archeologica allestita nel 2006, l&#8217;attuale Porta Palatina risale all&#8217;epoca romana, ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/reggia-di-venaria-reale\/\">Reggia di Venaria Reale<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/reggia-di-venaria-reale\/\" title=\"Reggia di Venaria Reale\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-royal-de-la-venaria-turin_5692-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Reggia di Venaria Reale\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-royal-de-la-venaria-turin_5692-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-royal-de-la-venaria-turin_5692-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-royal-de-la-venaria-turin_5692-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palais-royal-de-la-venaria-turin_5692-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nLa Reggia di Venaria fu eretta su iniziativa del duca Carlo Emanuele II dall&#8217;architetto Amedeo ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/altri-luoghi-e-monumenti-di-torino\/\">Altri luoghi e monumenti di Torino<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/altri-luoghi-e-monumenti-di-torino\/\" title=\"Altri luoghi e monumenti di Torino\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-palazzo-di-citta-torino_7984-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Altri luoghi e monumenti di Torino\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-palazzo-di-citta-torino_7984-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-palazzo-di-citta-torino_7984-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-palazzo-di-citta-torino_7984-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-palazzo-di-citta-torino_7984-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nQuesto articolo completa la pagina &#8220;Cosa vedere a Torino?&#8221; con immagini dei monumenti aggiuntivi.\nCuriosit\u00e0 della ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/palazzina-di-caccia-di-stupinigi\/\">Palazzina di caccia di Stupinigi<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/palazzina-di-caccia-di-stupinigi\/\" title=\"Palazzina di caccia di Stupinigi\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palazzina-di-caccia-di-stupinigi_5708-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Palazzina di caccia di Stupinigi\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palazzina-di-caccia-di-stupinigi_5708-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palazzina-di-caccia-di-stupinigi_5708-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palazzina-di-caccia-di-stupinigi_5708-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/palazzina-di-caccia-di-stupinigi_5708-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nLa Palazzina di Caccia di Stupinigi \u00e8 sicuramente uno degli edifici pi\u00f9 belli del genere ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-di-rivoli\/\">Castello di Rivoli<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-di-rivoli\/\" title=\"Castello di Rivoli\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/chateau-de-rivoli_5704-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Castello di Rivoli\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/chateau-de-rivoli_5704-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/chateau-de-rivoli_5704-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/chateau-de-rivoli_5704-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/chateau-de-rivoli_5704-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Castello di Rivoli risale al IX e X secolo, diventando nel 1280 propriet\u00e0 della ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/colline-torinesi\/\">Colline Torinesi<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/colline-torinesi\/\" title=\"Colline Torinesi\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/colle-torinese_6177-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Colline Torinesi\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/colle-torinese_6177-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/colle-torinese_6177-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/colle-torinese_6177-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/colle-torinese_6177-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nLe Colline Torinesi si trovano appena ad est di Torino e si estendono per alcune ...<\/div><\/li><\/ul>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Castello di Moncalieri \u00e8 un&#8217;altra delle residenze sabaude, che si trova nei dintorni di Torino. In cima al paese di Moncalieri fu costruito nel XVII secolo ampliando una fortezza medievale.Il palazzo fu pi\u00f9 volte dimora dei sovrani e dei nobili, tra cui Emanuele Filiberto o Carlo Emanuele I che decise di ingrandirlo, facendo intervenire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16353,"parent":25207,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"tags":[],"categorie_page":[97],"region_italie":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Castello Reale di Moncalieri - Bellitalie<\/title>\n<meta name=\"description\" content=\"Il Castello di Moncalieri \u00e8 una residenza sabauda vicino a Torino costruito nel XVII secolo, di cui si visitano gli appartamenti nobili\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castello Reale di Moncalieri - Bellitalie\" \/>\n<meta property=\"og:description\" content=\"Il Castello di Moncalieri \u00e8 una residenza sabauda vicino a Torino costruito nel XVII secolo, di cui si visitano gli appartamenti nobili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/\" \/>\n<meta property=\"og:site_name\" content=\"Bellitalie\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T08:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bellitalie.org\/#website\",\"url\":\"https:\/\/www.bellitalie.org\/\",\"name\":\"Bellitalie\",\"description\":\"Regioni, citt\\u00e0 e patrimonio dell'Italia da nord a sud\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bellitalie.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg\",\"contentUrl\":\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg\",\"width\":1200,\"height\":800,\"caption\":\"castello-di-moncalieri_5716\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#webpage\",\"url\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/\",\"name\":\"Castello Reale di Moncalieri - Bellitalie\",\"isPartOf\":{\"@id\":\"https:\/\/www.bellitalie.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#primaryimage\"},\"datePublished\":\"2021-09-01T11:35:00+00:00\",\"dateModified\":\"2023-10-11T08:50:21+00:00\",\"description\":\"Il Castello di Moncalieri \\u00e8 una residenza sabauda vicino a Torino costruito nel XVII secolo, di cui si visitano gli appartamenti nobili\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.bellitalie.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piemonte\",\"item\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Torino\",\"item\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Castello Reale di Moncalieri\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bellitalie.org\/#\/schema\/person\/6f25c64f0b5df6df0b93a2be44045da5\",\"name\":\"Bellitalie\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bellitalie.org\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Bellitalie\"},\"sameAs\":[\"https:\/\/www.bellitalie.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castello Reale di Moncalieri - Bellitalie","description":"Il Castello di Moncalieri \u00e8 una residenza sabauda vicino a Torino costruito nel XVII secolo, di cui si visitano gli appartamenti nobili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/","og_locale":"it_IT","og_type":"article","og_title":"Castello Reale di Moncalieri - Bellitalie","og_description":"Il Castello di Moncalieri \u00e8 una residenza sabauda vicino a Torino costruito nel XVII secolo, di cui si visitano gli appartamenti nobili","og_url":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/","og_site_name":"Bellitalie","article_modified_time":"2023-10-11T08:50:21+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bellitalie.org\/#website","url":"https:\/\/www.bellitalie.org\/","name":"Bellitalie","description":"Regioni, citt\u00e0 e patrimonio dell'Italia da nord a sud","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bellitalie.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg","contentUrl":"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/06\/castello-di-moncalieri_5716.jpg","width":1200,"height":800,"caption":"castello-di-moncalieri_5716"},{"@type":"WebPage","@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#webpage","url":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/","name":"Castello Reale di Moncalieri - Bellitalie","isPartOf":{"@id":"https:\/\/www.bellitalie.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#primaryimage"},"datePublished":"2021-09-01T11:35:00+00:00","dateModified":"2023-10-11T08:50:21+00:00","description":"Il Castello di Moncalieri \u00e8 una residenza sabauda vicino a Torino costruito nel XVII secolo, di cui si visitano gli appartamenti nobili","breadcrumb":{"@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/castello-reale-di-moncalieri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bellitalie.org\/it\/"},{"@type":"ListItem","position":2,"name":"Piemonte","item":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/"},{"@type":"ListItem","position":3,"name":"Torino","item":"https:\/\/www.bellitalie.org\/it\/destinazione\/piemonte\/torino\/"},{"@type":"ListItem","position":4,"name":"Castello Reale di Moncalieri"}]},{"@type":"Person","@id":"https:\/\/www.bellitalie.org\/#\/schema\/person\/6f25c64f0b5df6df0b93a2be44045da5","name":"Bellitalie","image":{"@type":"ImageObject","@id":"https:\/\/www.bellitalie.org\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Bellitalie"},"sameAs":["https:\/\/www.bellitalie.org"]}]}},"_links":{"self":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25480"}],"collection":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination"}],"about":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/types\/destination"}],"author":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/comments?post=25480"}],"version-history":[{"count":2,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25480\/revisions"}],"predecessor-version":[{"id":25483,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25480\/revisions\/25483"}],"up":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/media\/16353"}],"wp:attachment":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/media?parent=25480"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/tags?post=25480"},{"taxonomy":"categorie_page","embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/categorie_page?post=25480"},{"taxonomy":"region_italie","embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/region_italie?post=25480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}