{"id":25991,"date":"2021-09-05T10:52:00","date_gmt":"2021-09-05T08:52:00","guid":{"rendered":"https:\/\/www.bellitalie.org\/destination\/lombardia\/monza\/"},"modified":"2023-10-17T11:33:55","modified_gmt":"2023-10-17T09:33:55","slug":"monza-e-la-brianza","status":"publish","type":"destination","link":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/","title":{"rendered":"Monza e la Brianza"},"content":{"rendered":"\n<h2>Monza<\/h2>\n<p>Situata nel cuore della <strong>Brianza<\/strong>, vicino a Milano sulle rive del Lambro, <strong>Monza<\/strong> \u00e8 la terza citt\u00e0 pi\u00f9 popolosa della Lombardia. Il suo nome evoca inizialmente il famoso circuito automobilistico, ma merita una visita per la sua cattedrale gotica e i suoi tesori che risalgono alla regina Teodolinda, e per la <strong>Villa Reale<\/strong> con il suo grande parco di 700 ettari attraversato dal circuito.<\/p>\n<h3>Cattedrale di Monza<\/h3>\n<p>La <strong>cattedrale<\/strong> risale al VII secolo d.C., con la regina longobarda Teodolinda. Si tratta di un edificio gotico del XIII-XIV secolo ha una ricca facciata, fiancheggiata da un campanile meno bello del 1606, che conserva tesori e la preziosa <strong>Cappella Teodolinda<\/strong> fu dipinta dagli <em>Zavattari<\/em> nel 1444. Sul suo altare si trova la corona di ferro di cui un anello sarebbe stato forgiato con un chiodo della Croce di Cristo. Ornata d&#8217;oro e di gioielli, risalenti ai V-VIII secoli, serviva nel medioevo all&#8217;incoronazione dei re in Italia, come Carlo Magno.<\/p>\n\n\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19591\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-300x200.jpg\" alt=\"foto del duomo di monza\" class=\"wp-image-19591\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Duomo di Monza<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/villa-reale-monza_8034.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19594\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/villa-reale-monza_8034-300x200.jpg\" alt=\"foto della villa reale di monza_8034\" class=\"wp-image-19594\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/villa-reale-monza_8034-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/villa-reale-monza_8034-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/villa-reale-monza_8034-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/villa-reale-monza_8034.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Villa Reale di Monza<\/figcaption><\/figure>\n<\/figure>\n\n\n<h3>Villa Reale e Parco di Monza<\/h3>\n<p>La <strong>Villa Reale<\/strong> (1777-1870) fu la residenza della corte asburgica, associata al grande parco attraversato dal circuito automobilistico.<br \/>Questo palazzo reale, che conta settecento sale, fu costruito sotto il dominio austriaco sul Ducato di Monza, a partire dal 1777 da <strong>Ferdinando d&#8217;Asburgo<\/strong> come residenza di campagna, realizzato da <strong>Piermarini<\/strong> all&#8217;epoca in cui ridisegn\u00f2 Milano.<br \/>La sua grande facciata neoclassica si affaccia su un&#8217;eminenza sopra il parco, con un famoso roseto.<\/p>\n<p>Di fronte alla villa reale, il parco \u00e8 vasto di 700 ettari. \u00c8 il quarto parco recintato pi\u00f9 grande d&#8217;Europa, circondato da mura, con prati, boschi, laghi, un fiume e edifici neoclassici. Si pu\u00f2 visitare a piedi, in bicicletta o con il trenino.<\/p>\n<h3>Circuito automobilistico di Monza<\/h3>\n<p>Non lontano dalla Villa Reale, l&#8217;Autodromo Nazionale di Monza \u00e8 dal 1922 un tempio della Formula 1.<\/p>\n<h3>Altri monumenti e musei<\/h3>\n<p>Il centro della citt\u00e0 si distingue anche con l&#8217;<strong>Arengario<\/strong>, l&#8217;antico palazzo del XIII secolo e municipio, la torre del XIII secolo detta <strong>Teodolinda<\/strong>, le chiese di San Pietro Martire, Santa Maria in Strada e Santa Maria delle Grazie (santuario francescano del XV secolo), o ancora la Cappella Espiatoria del XX secolo con i suoi bellissimi mosaici.<br \/>Antichi ponti attraversano il Lambro, come il monumentale Ponte dei Leoni o il pi\u00f9 antico Ponte Nuovo del XIV secolo.<br \/>Il <strong>Museo Civico di Monza<\/strong>, riaperto nel 2014, raccoglie 140 opere che raccontano la storia della citt\u00e0, nel complesso medievale della Casa degli Umiliati.<br \/>All&#8217;esterno della citt\u00e0 si pu\u00f2 passeggiare lungo il Lambro, a piedi o in bicicletta, e visitare alcuni villaggi della Brianza: Macherio, Carate, Arosio e Inverigo pi\u00f9 a nord.<\/p>\n\n\n<figure class=\"wp-container-4 wp-block-gallery-3 wp-block-gallery has-nested-images columns-5 is-cropped\">\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/arengario-monza_8012.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19597\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/arengario-monza_8012-200x300.jpg\" alt=\"foto dell'arengario-monza_8012\" class=\"wp-image-19597\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/arengario-monza_8012-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/arengario-monza_8012-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/arengario-monza_8012-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/arengario-monza_8012.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Arengario (XIII)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palais-arengario-monza_8031.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19633\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palais-arengario-monza_8031-300x200.jpg\" alt=\"foto dell'arengario-monza_8031\" class=\"wp-image-19633\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palais-arengario-monza_8031-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palais-arengario-monza_8031-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palais-arengario-monza_8031-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palais-arengario-monza_8031.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Arengario (XIII)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-arengario-monza_8014.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19636\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-arengario-monza_8014-300x200.jpg\" alt=\"foto dell'arengario-monza_8014\" class=\"wp-image-19636\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-arengario-monza_8014-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-arengario-monza_8014-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-arengario-monza_8014-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/palazzo-arengario-monza_8014.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Arengario (XIII)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8020.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19612\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8020-200x300.jpg\" alt=\"foto duomo-di-monza_8020\" class=\"wp-image-19612\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8020-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8020-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8020-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8020.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Piazza del duomo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8019.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19609\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8019-200x300.jpg\" alt=\"foto duomo-di-monza_8019\" class=\"wp-image-19609\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8019-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8019-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8019-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-di-monza_8019.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Duomo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/facade-rosace-duomo-di-monza_8086.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19618\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/facade-rosace-duomo-di-monza_8086-300x200.jpg\" alt=\"foto della facciata del duomo di monza\" class=\"wp-image-19618\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/facade-rosace-duomo-di-monza_8086-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/facade-rosace-duomo-di-monza_8086-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/facade-rosace-duomo-di-monza_8086-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/facade-rosace-duomo-di-monza_8086.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Duomo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8026.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19600\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8026-300x200.jpg\" alt=\"basilique-duomo-di-monza_8026\" class=\"wp-image-19600\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8026-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8026-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8026-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8026.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Duomo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8082.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19624\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8082-300x200.jpg\" alt=\"interno-duomo-di-monza_8082\" class=\"wp-image-19624\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8082-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8082-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8082-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8082.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Duomo, ex evangelicatorio (Matteo da Campione)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8077.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19603\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8077-200x300.jpg\" alt=\"foto cappella-di-teodolinda-duomo-di-monza_8077\" class=\"wp-image-19603\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8077-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8077-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8077-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8077.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Cappella Teodolinda (XV)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8078.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19606\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8078-300x200.jpg\" alt=\"foto cappella-di-teodolinda-duomo-di-monza_8078\" class=\"wp-image-19606\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8078-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8078-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8078-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cappella-di-teodolinda-duomo-di-monza_8078.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Cappella Teodolinda (XV)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8081.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19621\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8081-300x200.jpg\" alt=\"interno-duomo-di-monza_8081\" class=\"wp-image-19621\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8081-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8081-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8081-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8081.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Cappella Teodolinda (XV)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19615\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076-200x300.jpg\" alt=\"ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076\" class=\"wp-image-19615\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ex-evangelicatorio-di-matteo-da-campione-duomo-di-monza_8076.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Duomo, ex evangelicatorio (Matteo da Campione)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8084.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19627\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8084-300x200.jpg\" alt=\"interno-duomo-di-monza_8084\" class=\"wp-image-19627\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8084-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8084-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8084-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/interno-duomo-di-monza_8084.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Duomo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/monumento-a-vittorio-emmanuele-ii-monza_8067.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19630\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/monumento-a-vittorio-emmanuele-ii-monza_8067-300x200.jpg\" alt=\"monumento-a-vittorio-emmanuele-ii-monza_8067\" class=\"wp-image-19630\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/monumento-a-vittorio-emmanuele-ii-monza_8067-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/monumento-a-vittorio-emmanuele-ii-monza_8067-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/monumento-a-vittorio-emmanuele-ii-monza_8067-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/monumento-a-vittorio-emmanuele-ii-monza_8067.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Monumento a Vittorio-Emanuele II <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8061.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19645\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8061-300x200.jpg\" alt=\"parco-di-monza_8061\" class=\"wp-image-19645\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8061-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8061-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8061-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8061.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Parco di Monza<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8054.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19639\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8054-300x200.jpg\" alt=\"parco-di-monza_8054\" class=\"wp-image-19639\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8054-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8054-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8054-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8054.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Parco di Monza<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8059.jpg\"><img loading=\"lazy\" width=\"300\" height=\"200\" data-id=\"19642\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8059-300x200.jpg\" alt=\"parco-di-monza_8059\" class=\"wp-image-19642\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8059-300x200.jpg 300w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8059-1024x683.jpg 1024w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8059-768x512.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/parco-di-monza_8059.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Parco di Monza<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/torre-medievale-teodolinda-monza_8028.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19651\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/torre-medievale-teodolinda-monza_8028-200x300.jpg\" alt=\"torre-medievale-teodolinda-monza_8028\" class=\"wp-image-19651\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/torre-medievale-teodolinda-monza_8028-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/torre-medievale-teodolinda-monza_8028-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/torre-medievale-teodolinda-monza_8028-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/torre-medievale-teodolinda-monza_8028.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Torre Teodolinda (XIII)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ponte-monza_8029.jpg\"><img loading=\"lazy\" width=\"200\" height=\"300\" data-id=\"19648\"  src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ponte-monza_8029-200x300.jpg\" alt=\"ponte-monza_8029\" class=\"wp-image-19648\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ponte-monza_8029-200x300.jpg 200w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ponte-monza_8029-683x1024.jpg 683w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ponte-monza_8029-768x1152.jpg 768w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/ponte-monza_8029.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><figcaption>Ponte dei Leoni<\/figcaption><\/figure>\n<\/figure>\n\n\n<h2>La Brianza<\/h2>\n<p>La <strong>Brianza<\/strong> \u00e8 una zona geografica situata a nord di Milano, di cui Monza \u00e8 il cuore, a sud del Lago di Como, costituita da una pianura a sud-ovest, e da colline a nord-est, con diversi laghetti.<br \/>Il suo nome deriva dal termine celtico <em>Brig<\/em>, che significa collina, ma fonti lo collegano alla storia di Brianteo, un eroe dei compagni del principe gallico Bellovese che avrebbe occupato l&#8217;Insubria e fondato l&#8217;antica Mediolanum. Una terza tesi lo attribuisce alla trib\u00f9 celtica Brigantia emigrata in Lombardia.<br \/>Nel cuore della seconda rivoluzione industriale, \u00e8 diventata una delle regioni pi\u00f9 densamente popolate d&#8217;Italia.<\/p>\n<h3>Vimercate<\/h3>\n<p><strong>Vimercate<\/strong> \u00e8 una citt\u00e0 attiva della Brianza, con testimonianze romane e anche medievali come la Chiesa di Santo Stefano o il Ponte di San Rocco, esempio unico di ponte romano fortificato dai longobardi, e il Casino di caccia Borromeo.<br \/>Sul suo territorio furono costruite ville nobiliari e di villeggiatura a partire dal XVI secolo, come la grandiosa Villa Gallarati Scotti, il Palazzo Trotti e la neoclassica Villa Sottocasa, oggi sede del MUST Museo del territorio.<\/p>\n<h3>Cesano Maderno<\/h3>\n<p><strong>Cesano Maderno<\/strong> \u00e8 una delle citt\u00e0 pi\u00f9 importanti della provincia con un notevole centro storico, tra cui il cosiddetto torrazzo, il resto delle fortificazioni medievali, la villa e palazzo Arese Borromeo del XVII secolo, gli oratori e Santo Stefano Protomartire, o ancora l&#8217;Oasi Lipu di Cesano.<br \/>Il Palazzo Arese Borromeo \u00e8 uno dei pi\u00f9 bei palazzi della zona, costruito nella seconda met\u00e0 del XVII secolo, con un&#8217;ala del XVI secolo, splendidi saloni, gallerie e appartamenti, tra cui straordinari affreschi, e il giardino.<\/p>\n<h3>Ecomuseo Adda di Leonardo<\/h3>\n<p>L&#8217;<strong>Ecomuseo Adda di Leonardo<\/strong> si trova all&#8217;interno del Parco dell&#8217;Adda Nord, lungo il fiume Adda, per valorizzare il patrimonio naturale locale, con particolare attenzione al soggiorno di Leonardo da Vinci in Lombardia.<br \/>Il percorso \u00e8 lungo 21 km su 18 tappe, con uno dei due esemplari del &#8220;traghetto di Leonardo&#8221;, immaginato nel 1513.<\/p>\n<h3>Montevecchia<\/h3>\n<p><strong>Montevecchia<\/strong>, a nord-est della Brianza, \u00e8 sede del parco regionale di Montevecchia e della valle del Curone, con i suoi boschi e la sua produzione agricola, tra cui i suoi formaggi. C&#8217;\u00e8 anche un Uomo di Neanderthal vecchio di 60.000 anni e uno di Homo sapiens vecchio di 32.000 anni.<br \/>Il santuario della Beata Vergine del Carmelo \u00e8 di origine medievale, situato in cima alla collina con un paesaggio sulla Brianza. Si trova anche Villa Albertoni Agnesi costruita nel XVIII secolo, in stile rococ\u00f2.<\/p>\n<h3>Seregno<\/h3>\n<p>Nella bassa Brianza, il comune di <strong>Seregno<\/strong> conserva un antico centro, tra cui vicoli appartenenti ai vari paesi, un antico pozzo, la basilica collegiata di San Giuseppe, il santuario neogotico di Nostra Signora di Santa Valeria, l&#8217;abbazia dei Monaci Olivetani di San Benedetto e la Torre Barbarossa.<\/p>\n<p>\u00a0<\/p>\n<h2>Informazioni<\/h2>\n<ul>\n<li>Articoli Wikipedia : <a href=\"https:\/\/it.wikipedia.org\/wiki\/Brianza\" target=\"_blank\" rel=\"noopener\">Brianza<\/a>, <a href=\"https:\/\/it.wikipedia.org\/wiki\/Monza\" target=\"_blank\" rel=\"noopener\">Monza<\/a><\/li>\n<li>Portali turistici : <a href=\"https:\/\/turismo.monza.it\/\" target=\"_blank\" rel=\"noopener\">turismo.monza.it<\/a>, <a href=\"https:\/\/www.in-lombardia.it\/it\/turismo-in-lombardia\/monza-turismo\" target=\"_blank\" rel=\"noopener\">www.in-lombardia.it<\/a><\/li>\n<\/ul>\n<div id=\"meteo\"><br\/>\r\n\t\t<h2>Meteo a Monza<\/h2>\r\n<p><!-- Inizio codice ilMeteo.it --><\/p>\r\n<p><iframe src=\"https:\/\/www.ilmeteo.it\/box\/previsioni.php?citta=4474&amp;type=day1&amp;width=600&amp;ico=1&amp;lang=ita&amp;days=6&amp;font=Arial&amp;fontsize=12&amp;bg=FFFFFF&amp;fg=000000&amp;bgtitle=F0E8DF&amp;fgtitle=3D3D3D&amp;bgtab=FBFAF5&amp;fglink=1361A3\" width=\"600\" height=\"240\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\r\n<p><!-- Fine codice ilMeteo.it --><\/p>\r\n<\/div>\n<h3>Cartina<\/h3>\n<div id=\"travelersmap-container-6a573a5ad4479\" class=\"travelersmap-container\" style=\"z-index: 1; min-height: 10px; min-width:10px; height:400px;width:100%; max-width:; max-height:; position:relative;\"><div style=\"position:absolute; z-index:-1;top: 50%;text-align: center;display: block;left: 50%;transform: translate(-50%,-50%);\">Travelers' Map is loading... <br> If you see this after your page is loaded completely, leafletJS files are missing.<\/div><\/div>\n<p>\u00a0<\/p>\n\n\n<div class=\"wp-container-7 wp-block-columns has-background\" style=\"background-color:#dfece5\">\n<div class=\"wp-container-5 wp-block-column\">\n<p><strong><a href=\"https:\/\/www.bellitalie.org\/it\/regione_italia\/lombardia\/\">Lombardia<\/a><\/strong><\/p>\n<ul class=\"lcp_catlist2\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/da-vedere-in-lombardia\/\">Da vedere in Lombardia<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/da-vedere-in-lombardia\/\" title=\"Da vedere in Lombardia\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Da vedere in Lombardia\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nMilano \nMilano, il capoluogo lombardo, \u00e8 il centro economico e finanziario dell&#8217;Italia con la sede ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/milano\/\">Milano<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/milano\/\" title=\"Milano\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-de-milan_8091-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Milano\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-de-milan_8091-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-de-milan_8091-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-de-milan_8091-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/duomo-de-milan_8091-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nPrincipale citt\u00e0 economica e finanziaria d&#8217;Italia, centro internazionale della moda e dell&#8217;eleganza, Milano \u00e8 una ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-maggiore\/\">Lago Maggiore<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-maggiore\/\" title=\"Lago Maggiore\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago Maggiore\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-majeur_7509-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Lago Maggiore \u00e8 una delle pi\u00f9 belle destinazioni del nord Italia, la cui sponda ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-di-como\/\">Lago di Como<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-di-como\/\" title=\"Lago di Como\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lago_di_como_1496-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago di Como\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lago_di_como_1496-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lago_di_como_1496-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lago_di_como_1496-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lago_di_como_1496-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nNon solo il Lago di Como \u00e8 il lago pi\u00f9 profondo d&#8217;Italia, ma \u00e8 anche ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/veneto\/lago-di-garda\/\">Lago di Garda<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/veneto\/lago-di-garda\/\" title=\"Lago di Garda\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/cote-lac-de-garde-malcesine-brenzone_9766-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago di Garda\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/cote-lac-de-garde-malcesine-brenzone_9766-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/cote-lac-de-garde-malcesine-brenzone_9766-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/cote-lac-de-garde-malcesine-brenzone_9766-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/cote-lac-de-garde-malcesine-brenzone_9766-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl Lago di Garda \u00e8 il pi\u00f9 grande lago d&#8217;Italia, situato tra Brescia ad ovest ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/bergamo\/\">Bergamo<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/bergamo\/\" title=\"Bergamo\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bergame_1513-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Bergamo\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bergame_1513-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bergame_1513-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bergame_1513-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bergame_1513-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nLa citt\u00e0 alta di Bergamo \u00e8 il pi\u00f9 bel centro medievale di Lombardia, protetto da ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/brescia\/\">Brescia<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/brescia\/\" title=\"Brescia\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/brescia_1556-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Brescia\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/brescia_1556-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/brescia_1556-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/brescia_1556-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/brescia_1556-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nBrescia, la seconda citt\u00e0 pi\u00f9 grande della Lombardia, non gode della fama che meriterebbe. \u00c8 ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/mantova\/\">Mantova<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/mantova\/\" title=\"Mantova\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/laghi-mincio-mantova_0704-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Mantova\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/laghi-mincio-mantova_0704-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/laghi-mincio-mantova_0704-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/laghi-mincio-mantova_0704-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/laghi-mincio-mantova_0704-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nMantova \u00e8 una meravigliosa citt\u00e0 della pianura padana, iscritta dall&#8217;Unesco al Patrimonio dell&#8217;Umanit\u00e0 nel 2008. ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/cremona\/\">Cremona<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/cremona\/\" title=\"Cremona\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cremone_7949-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Cremona\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cremone_7949-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cremone_7949-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cremone_7949-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/cremone_7949-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nCremona \u00e8 una citt\u00e0 lombarda di circa 71.000 abitanti (nel 2021), situata nella pianura padana, ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/como\/\">Como<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/como\/\" title=\"Como\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/come_1469-1-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Como\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/come_1469-1-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/come_1469-1-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/come_1469-1-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/come_1469-1-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nComo \u00e8 con Lecco la citt\u00e0 pi\u00f9 grande del Lago di Como, con circa 84.000 ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/pavia\/\">Pavia<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/pavia\/\" title=\"Pavia\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/pavie_7921-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Pavia\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/pavie_7921-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/pavie_7921-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/pavie_7921-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/pavie_7921-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nPavia \u00e8 una graziosa citt\u00e0 sulle sponde del Ticino a 40 km a sud di ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/sirmione\/\">Sirmione<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/sirmione\/\" title=\"Sirmione\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/sirmione_1567-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Sirmione\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/sirmione_1567-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/sirmione_1567-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/sirmione_1567-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/sirmione_1567-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nSirmione \u00e8 la citt\u00e0 emblematica del Lago di Garda, una delle destinazioni pi\u00f9 affascinanti della ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/vigevano\/\">Vigevano<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/vigevano\/\" title=\"Vigevano\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-ducale-vigevano_6578-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Vigevano\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-ducale-vigevano_6578-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-ducale-vigevano_6578-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-ducale-vigevano_6578-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/piazza-ducale-vigevano_6578-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nVigevano \u00e8 una bellissima citt\u00e0 d&#8217;arte, eppure poco conosciuta, tra Milano, Pavia e Novara, a ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/bellagio\/\">Bellagio<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/bellagio\/\" title=\"Bellagio\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bellagio_1529-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Bellagio\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bellagio_1529-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bellagio_1529-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bellagio_1529-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/bellagio_1529-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nAll&#8217;incrocio dei due bracci meridionali del Lago di Como, Bellagio \u00e8 un grazioso borgo designato ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-d-iseo\/\">Lago d&#8217;Iseo<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-d-iseo\/\" title=\"Lago d&#039;Iseo\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago d&#039;Iseo\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-iseo_7534-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nSituato tra Bergamo e Brescia, il piccolo Lago d&#8217;Iseo \u00e8 un sito di carattere in ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-d-idro-e-valle-sabbia\/\">Lago d&#8217;Idro e Valle Sabbia<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/lago-d-idro-e-valle-sabbia\/\" title=\"Lago d&#039;Idro e Valle Sabbia\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-idro_7540-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Lago d&#039;Idro e Valle Sabbia\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-idro_7540-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-idro_7540-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-idro_7540-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/lac-d-idro_7540-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nSeparato dal Lago di Garda da una montagna, il bellissimo piccolo Lago d&#8217;Idro arroccato a ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/varese\/\">Varese<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/varese\/\" title=\"Varese\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/palazzo-estense-varese_7161-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Varese\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/palazzo-estense-varese_7161-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/palazzo-estense-varese_7161-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/palazzo-estense-varese_7161-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2023\/09\/palazzo-estense-varese_7161-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nVicino a Como e Milano, tra laghi e montagne, Varese \u00e8 una citt\u00e0 piuttosto ignorata ...<\/div><\/li><li><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/val-camonica\/\">Val Camonica<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/val-camonica\/\" title=\"Val Camonica\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/foppe-di-nadro-parc-gravures-rupestres-de-ceto-cimbergo-paspardo_8516-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Val Camonica\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/foppe-di-nadro-parc-gravures-rupestres-de-ceto-cimbergo-paspardo_8516-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/foppe-di-nadro-parc-gravures-rupestres-de-ceto-cimbergo-paspardo_8516-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/foppe-di-nadro-parc-gravures-rupestres-de-ceto-cimbergo-paspardo_8516-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/foppe-di-nadro-parc-gravures-rupestres-de-ceto-cimbergo-paspardo_8516-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nIl fiume Oglio discende la Val Camonica per circa 80 km, dal Passo del Tonale ...<\/div><\/li><li class=\"current\"><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/\">Monza e la Brianza<\/a><a href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/\" title=\"Monza e la Brianza\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-150x150.jpg\" class=\"lcp_thumbnail wp-post-image\" alt=\"Monza e la Brianza\" loading=\"lazy\" srcset=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-150x150.jpg 150w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-50x50.jpg 50w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-80x80.jpg 80w, https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024-75x75.jpg 75w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><div class=\"lcp_excerpt\">\nMonza\nSituata nel cuore della Brianza, vicino a Milano sulle rive del Lambro, Monza \u00e8 la ...<\/div><\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-container-6 wp-block-column\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Monza Situata nel cuore della Brianza, vicino a Milano sulle rive del Lambro, Monza \u00e8 la terza citt\u00e0 pi\u00f9 popolosa della Lombardia. Il suo nome evoca inizialmente il famoso circuito automobilistico, ma merita una visita per la sua cattedrale gotica e i suoi tesori che risalgono alla regina Teodolinda, e per la Villa Reale con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19593,"parent":24678,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"tags":[],"categorie_page":[113],"region_italie":[84],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monza e la Brianza - Bellitalie<\/title>\n<meta name=\"description\" content=\"Nel cuore della Brianza, Monza merita una visita per la sua cattedrale gotica, la Villa Reale con il suo grande parco vicino al circuito\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monza e la Brianza - Bellitalie\" \/>\n<meta property=\"og:description\" content=\"Nel cuore della Brianza, Monza merita una visita per la sua cattedrale gotica, la Villa Reale con il suo grande parco vicino al circuito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/\" \/>\n<meta property=\"og:site_name\" content=\"Bellitalie\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T09:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bellitalie.org\/#website\",\"url\":\"https:\/\/www.bellitalie.org\/\",\"name\":\"Bellitalie\",\"description\":\"Regioni, citt\\u00e0 e patrimonio dell'Italia da nord a sud\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bellitalie.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg\",\"contentUrl\":\"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg\",\"width\":1200,\"height\":800,\"caption\":\"basilique-duomo-di-monza_8024\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#webpage\",\"url\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/\",\"name\":\"Monza e la Brianza - Bellitalie\",\"isPartOf\":{\"@id\":\"https:\/\/www.bellitalie.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#primaryimage\"},\"datePublished\":\"2021-09-05T08:52:00+00:00\",\"dateModified\":\"2023-10-17T09:33:55+00:00\",\"description\":\"Nel cuore della Brianza, Monza merita una visita per la sua cattedrale gotica, la Villa Reale con il suo grande parco vicino al circuito\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.bellitalie.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lombardia\",\"item\":\"https:\/\/www.bellitalie.org\/it\/regione_italia\/lombardia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Monza e la Brianza\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bellitalie.org\/#\/schema\/person\/6f25c64f0b5df6df0b93a2be44045da5\",\"name\":\"Bellitalie\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bellitalie.org\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Bellitalie\"},\"sameAs\":[\"https:\/\/www.bellitalie.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monza e la Brianza - Bellitalie","description":"Nel cuore della Brianza, Monza merita una visita per la sua cattedrale gotica, la Villa Reale con il suo grande parco vicino al circuito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/","og_locale":"it_IT","og_type":"article","og_title":"Monza e la Brianza - Bellitalie","og_description":"Nel cuore della Brianza, Monza merita una visita per la sua cattedrale gotica, la Villa Reale con il suo grande parco vicino al circuito","og_url":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/","og_site_name":"Bellitalie","article_modified_time":"2023-10-17T09:33:55+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bellitalie.org\/#website","url":"https:\/\/www.bellitalie.org\/","name":"Bellitalie","description":"Regioni, citt\u00e0 e patrimonio dell'Italia da nord a sud","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bellitalie.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg","contentUrl":"https:\/\/www.bellitalie.org\/wp-content\/uploads\/2021\/09\/basilique-duomo-di-monza_8024.jpg","width":1200,"height":800,"caption":"basilique-duomo-di-monza_8024"},{"@type":"WebPage","@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#webpage","url":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/","name":"Monza e la Brianza - Bellitalie","isPartOf":{"@id":"https:\/\/www.bellitalie.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#primaryimage"},"datePublished":"2021-09-05T08:52:00+00:00","dateModified":"2023-10-17T09:33:55+00:00","description":"Nel cuore della Brianza, Monza merita una visita per la sua cattedrale gotica, la Villa Reale con il suo grande parco vicino al circuito","breadcrumb":{"@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bellitalie.org\/it\/destinazione\/lombardia\/monza-e-la-brianza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bellitalie.org\/it\/"},{"@type":"ListItem","position":2,"name":"Lombardia","item":"https:\/\/www.bellitalie.org\/it\/regione_italia\/lombardia\/"},{"@type":"ListItem","position":3,"name":"Monza e la Brianza"}]},{"@type":"Person","@id":"https:\/\/www.bellitalie.org\/#\/schema\/person\/6f25c64f0b5df6df0b93a2be44045da5","name":"Bellitalie","image":{"@type":"ImageObject","@id":"https:\/\/www.bellitalie.org\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Bellitalie"},"sameAs":["https:\/\/www.bellitalie.org"]}]}},"_links":{"self":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25991"}],"collection":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination"}],"about":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/types\/destination"}],"author":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/comments?post=25991"}],"version-history":[{"count":2,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25991\/revisions"}],"predecessor-version":[{"id":25994,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/25991\/revisions\/25994"}],"up":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/destination\/24678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/media\/19593"}],"wp:attachment":[{"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/media?parent=25991"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/tags?post=25991"},{"taxonomy":"categorie_page","embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/categorie_page?post=25991"},{"taxonomy":"region_italie","embeddable":true,"href":"https:\/\/www.bellitalie.org\/it\/wp-json\/wp\/v2\/region_italie?post=25991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}